{"id":32280,"date":"2025-12-01T14:01:07","date_gmt":"2025-12-01T11:01:07","guid":{"rendered":"https:\/\/mtroyal.com.tr\/fa\/?p=32280"},"modified":"2025-12-01T14:01:07","modified_gmt":"2025-12-01T11:01:07","slug":"%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86","status":"publish","type":"post","link":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/","title":{"rendered":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646"},"content":{"rendered":"<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u062a\u0648\u0644\u06cc\u062f \u0644\u0627\u0633\u062a\u06cc\u06a9\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u062f\u06cc\u06af\u0631 \u06cc\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0646\u06cc\u0633\u062a\u061b \u0628\u0644\u06a9\u0647 \u06cc\u06a9 \u0636\u0631\u0648\u0631\u062a \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0627\u0633\u062a. \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0646\u0647 \u062a\u0646\u0647\u0627 \u062a\u0623\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645\u06cc \u0628\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f \u0646\u0647\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062f\u0627\u0631\u062f\u060c \u0628\u0644\u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0639\u06cc\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u06cc\u0632\u0627\u0646 \u062f\u0648\u0627\u0645\u060c \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0648 \u062d\u062a\u06cc \u0627\u06cc\u0645\u0646\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0646\u0647\u0627\u06cc\u06cc \u0628\u0627\u0634\u062f. \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 (Acrylonitrile Butadiene) \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u067e\u0644\u06cc\u0645\u0631\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0644\u0627\u0633\u062a\u06cc\u06a9\u200c\u0633\u0627\u0632\u06cc \u0648 \u062a\u0648\u0644\u06cc\u062f \u0642\u0637\u0639\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u060c \u0646\u0642\u0634 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0627\u0631\u062a\u0642\u0627\u0621 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0645\u06cc\u200c\u062f\u0627\u0646\u0646\u062f \u06a9\u0647 \u0647\u0631\u06af\u0648\u0646\u0647 \u06a9\u0648\u062a\u0627\u0647\u06cc \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0639\u0645\u0631 \u0645\u0641\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0648 \u062d\u062a\u06cc \u062a\u0648\u0642\u0641 \u062e\u0637\u0648\u0637 \u062a\u0648\u0644\u06cc\u062f \u0645\u0646\u062c\u0631 \u0634\u0648\u062f.<\/p>\n<p>\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0627\u0632 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u0639\u062a\u0628\u0631\u060c \u0628\u0647 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647\u200c\u0627\u06cc \u0645\u0637\u0627\u0628\u0642 \u0628\u0627 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0648\u0627\u062f\u060c \u0646\u0647 \u062a\u0646\u0647\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0645\u0642\u0627\u0648\u0645\u062a \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0632\u0631\u06af \u0648 \u0628\u0627 \u06a9\u0646\u062a\u0631\u0644 \u062f\u0642\u06cc\u0642 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc\u060c \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0647\u06cc\u0646\u0647 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0645\u062a\u0631 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f. \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u06cc\u06a9 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0645\u0627\u0646\u0646\u062f MT Royal\u060c \u062a\u062c\u0631\u0628\u0647\u200c\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0623\u0645\u06cc\u0646 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f\u061b \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u062a\u0636\u0645\u06cc\u0646 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0634\u0641\u0627\u0641\u06cc\u062a \u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u06cc \u0631\u0642\u0627\u0628\u062a\u06cc \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0628\u0627\u0632\u0627\u0631 \u062c\u0647\u0627\u0646\u06cc\u060c \u0628\u0647 \u0635\u0648\u0631\u062a \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.<\/p>\n<p>\u0645\u0627 \u062f\u0631 MT Royal \u062f\u0631 \u0637\u0648\u0644 \u0633\u0627\u0644\u200c\u0647\u0627 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u062e\u062a\u0644\u0641\u060c \u062f\u06cc\u062f\u0647\u200c\u0627\u06cc\u0645 \u06a9\u0647 \u0645\u0648\u0641\u0642\u200c\u062a\u0631\u06cc\u0646 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u06a9\u0633\u0627\u0646\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0642\u0628\u0644 \u0627\u0632 \u0622\u063a\u0627\u0632 \u0647\u0631 \u067e\u0631\u0648\u0698\u0647\u060c \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642\u06cc \u0627\u0632 \u0646\u0648\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632\u060c \u0634\u0631\u0627\u06cc\u0637 \u06a9\u0627\u0631\u0628\u0631\u062f\u060c \u0645\u062d\u06cc\u0637 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0646\u0647\u0627\u06cc\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0627\u06cc\u0646 \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627 \u0628\u0647 \u0622\u0646\u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f \u0648 \u0627\u0632 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0647\u0634 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc\u060c \u062e\u0648\u0631\u062f\u06af\u06cc \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u06cc\u0627 \u062e\u0631\u0627\u0628\u06cc \u0633\u0631\u06cc\u0639 \u0645\u062d\u0635\u0648\u0644 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0628\u0647 \u0639\u0628\u0627\u0631\u062a \u062f\u06cc\u06af\u0631\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0635\u062d\u06cc\u062d \u0646\u0648\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\u060c \u062a\u0646\u0647\u0627 \u06cc\u06a9 \u062a\u0635\u0645\u06cc\u0645 \u062e\u0631\u06cc\u062f \u0646\u06cc\u0633\u062a\u061b \u0628\u0644\u06a9\u0647 \u06cc\u06a9 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u062f\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u062f\u0648\u0627\u0645 \u0645\u062d\u0635\u0648\u0644\u060c \u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u0636\u0627\u06cc\u062a \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0646\u0647\u0627\u06cc\u06cc.<\/p>\n<p>\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u06cc\u06a9 <strong>\u067e\u0644\u06cc\u0645\u0631 \u062a\u0631\u0645\u0648\u067e\u0644\u0627\u0633\u062a\u06cc\u06a9 \u0648 \u0627\u0644\u0627\u0633\u062a\u0648\u0645\u0631\u06cc<\/strong> \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062e\u0648\u0627\u0635 \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0648 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062e\u0627\u0635 \u062e\u0648\u062f\u060c \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0645\u062a\u0646\u0648\u0639\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0639\u0645\u062f\u062a\u0627\u064b \u0627\u0632 <strong>\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644\u060c \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0648 \u0627\u0633\u062a\u0627\u06cc\u0631\u0646<\/strong> \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0648 \u0628\u0633\u062a\u0647 \u0628\u0647 \u0646\u0633\u0628\u062a \u0627\u06cc\u0646 \u0645\u0648\u0646\u0648\u0645\u0631\u0647\u0627\u060c \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<ul>\n<li><strong>\u0645\u0642\u0627\u0648\u0645\u062a \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc:<\/strong> \u0645\u0642\u0627\u0648\u0645\u062a \u0628\u0627\u0644\u0627 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0631\u0648\u063a\u0646\u200c\u0647\u0627\u060c \u062d\u0644\u0627\u0644\u200c\u0647\u0627 \u0648 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0635\u0646\u0639\u062a\u06cc.<\/li>\n<li><strong>\u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc:<\/strong> \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0642\u0637\u0639\u0627\u062a \u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u06a9\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0634\u06a9\u0644\u200c\u067e\u0630\u06cc\u0631\u06cc \u0648 \u062f\u0648\u0627\u0645 \u062f\u0627\u0631\u0646\u062f.<\/li>\n<li><strong>\u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062d\u0631\u0627\u0631\u062a:<\/strong> \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062f\u0631 \u0645\u062d\u062f\u0648\u062f\u0647 \u062f\u0645\u0627\u06cc\u06cc \u0648\u0633\u06cc\u0639 \u0628\u062f\u0648\u0646 \u06a9\u0627\u0647\u0634 \u06a9\u06cc\u0641\u06cc\u062a.<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0635\u0646\u0627\u06cc\u0639 \u062e\u0648\u062f\u0631\u0648\u0633\u0627\u0632\u06cc\u060c \u0644\u0627\u0633\u062a\u06cc\u06a9\u200c\u0633\u0627\u0632\u06cc\u060c \u062a\u0648\u0644\u06cc\u062f \u0642\u0637\u0639\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648 \u062d\u062a\u06cc \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u067e\u0632\u0634\u06a9\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<hr \/>\n<style>#vir-st-container.virmuni-smart-table-blue {border-color: #132a35 !important; background-color: #132a35 !important;}<\/style><div id=\"vir-st-container\" class=\"vir-st-v1_0_0 counter-hierarchy vir-st-counter-rtl virmuni-smart-table-blue vir-st-container-direction\">\n<div class=\"vir-st-title-container\">\n<p class=\"vir-st-title \" >\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"vir-st-title-toggle\"><a href=\"#\" class=\"vir-st-pull-right vir-st-btn vir-st-btn-xs vir-st-btn-default vir-st-toggle\" aria-label=\"Toggle Smart Table\" role=\"button\"><label for=\"item-6a57ea84b2d4c\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"vir-st-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a57ea84b2d4c\"  type=\"checkbox\" id=\"item-6a57ea84b2d4c\"><\/a><\/span><\/div>\n<nav><ul class='vir-st-list vir-st-list-level-1 ' ><style>#vir-st-container ul li a.vir-st-heading-level-1 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-1' style='font-size: 18px!important;font-weight: 600!important;'><input type=\"checkbox\" id=\"iconPlusMinus-1\"\/><label for=\"iconPlusMinus-1\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-1 vir-st-heading-level-1\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%D8%A7%D8%B4%D8%AA%D8%A8%D8%A7%D9%87%D8%A7%D8%AA_%D8%B1%D8%A7%DB%8C%D8%AC_%D8%AF%D8%B1_%D8%AA%D8%A3%D9%85%DB%8C%D9%86_%D8%B5%D9%86%D8%B9%D8%AA%DB%8C\" title=\"\u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a \u0631\u0627\u06cc\u062c \u062f\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0635\u0646\u0639\u062a\u06cc\">\u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a \u0631\u0627\u06cc\u062c \u062f\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0635\u0646\u0639\u062a\u06cc<\/a><ul class='vir-st-list-level-2'><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-2\"\/><label for=\"iconPlusMinus-2\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-2 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%DB%B1_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%86%D9%88%D8%B9_%D9%86%D8%A7%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%BE%D9%84%DB%8C%D9%85%D8%B1\" title=\"\u06f1. \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u067e\u0644\u06cc\u0645\u0631\">\u06f1. \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u067e\u0644\u06cc\u0645\u0631<\/a><\/li><\/ul><\/li><style>#vir-st-container ul li a.vir-st-heading-level-1 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-1' style='font-size: 18px!important;font-weight: 600!important;'><input type=\"checkbox\" id=\"iconPlusMinus-3\"\/><label for=\"iconPlusMinus-3\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-3 vir-st-heading-level-1\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87%E2%80%8C%D9%87%D8%A7_%D9%88_%D9%86%DA%A9%D8%A7%D8%AA_%D8%B5%D9%86%D8%B9%D8%AA%DB%8C_%D9%88%DB%8C%DA%98%D9%87\" title=\"\u0645\u0642\u0627\u06cc\u0633\u0647\u200c\u0647\u0627 \u0648 \u0646\u06a9\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648\u06cc\u0698\u0647\">\u0645\u0642\u0627\u06cc\u0633\u0647\u200c\u0647\u0627 \u0648 \u0646\u06a9\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648\u06cc\u0698\u0647<\/a><ul class='vir-st-list-level-2'><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-4\"\/><label for=\"iconPlusMinus-4\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-4 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%DB%B2_%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%AC%D9%87_%D8%A8%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%A8%DB%8C%D9%86%E2%80%8C%D8%A7%D9%84%D9%85%D9%84%D9%84%DB%8C\" title=\"\u06f2. \u0639\u062f\u0645 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc\">\u06f2. \u0639\u062f\u0645 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc<\/a><\/li><\/ul><\/li><style>#vir-st-container ul li a.vir-st-heading-level-1 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-1' style='font-size: 18px!important;font-weight: 600!important;'><input type=\"checkbox\" id=\"iconPlusMinus-5\"\/><label for=\"iconPlusMinus-5\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-5 vir-st-heading-level-1\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%D9%86%DA%A9%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C_%D8%AF%D8%B1_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D9%88_%D8%B2%D9%86%D8%AC%DB%8C%D8%B1%D9%87_%D8%AA%D8%A3%D9%85%DB%8C%D9%86\" title=\"\u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0632\u0646\u062c\u06cc\u0631\u0647 \u062a\u0623\u0645\u06cc\u0646\">\u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0632\u0646\u062c\u06cc\u0631\u0647 \u062a\u0623\u0645\u06cc\u0646<\/a><ul class='vir-st-list-level-2'><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-6\"\/><label for=\"iconPlusMinus-6\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-6 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%DB%B3_%D8%AA%D8%A3%D9%85%DB%8C%D9%86%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D8%BA%DB%8C%D8%B1%D9%82%D8%A7%D8%A8%D9%84_%D8%A7%D8%B9%D8%AA%D9%85%D8%A7%D8%AF\" title=\"\u06f3. \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f\">\u06f3. \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f<\/a><\/li><\/ul><\/li><style>#vir-st-container ul li a.vir-st-heading-level-1 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-1' style='font-size: 18px!important;font-weight: 600!important;'><input type=\"checkbox\" id=\"iconPlusMinus-7\"\/><label for=\"iconPlusMinus-7\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-7 vir-st-heading-level-1\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%D9%BE%D8%B1%D8%B3%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%BE%D8%B1%D8%AA%DA%A9%D8%B1%D8%A7%D8%B1_%D9%85%D8%AF%DB%8C%D8%B1%D8%A7%D9%86_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7\" title=\"\u067e\u0631\u0633\u0634\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u06a9\u0631\u0627\u0631 \u0645\u062f\u06cc\u0631\u0627\u0646 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627\">\u067e\u0631\u0633\u0634\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u06a9\u0631\u0627\u0631 \u0645\u062f\u06cc\u0631\u0627\u0646 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627<\/a><ul class='vir-st-list-level-2'><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-8\"\/><label for=\"iconPlusMinus-8\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-8 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#1_%DA%86%D9%87_%D8%AA%D9%81%D8%A7%D9%88%D8%AA%DB%8C_%D8%A8%DB%8C%D9%86_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D9%85%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF_%D9%88_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D9%85%D9%86%D8%A7%D8%B3%D8%A8%E2%80%8C%D8%AA%D8%B1%DB%8C%D9%86_%D9%86%D9%88%D8%B9_%D8%B1%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%B1%D8%AF%D8%9F\" title=\"1. \u0686\u0647 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0646\u0648\u0639 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u061f\">1. \u0686\u0647 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0646\u0648\u0639 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u061f<\/a><\/li><\/ul><\/li><style>#vir-st-container ul li a.vir-st-heading-level-1 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-1' style='font-size: 18px!important;font-weight: 600!important;'><input type=\"checkbox\" id=\"iconPlusMinus-9\"\/><label for=\"iconPlusMinus-9\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-9 vir-st-heading-level-1\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\" title=\"\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc\">\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<\/a><ul class='vir-st-list-level-2'><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-10\"\/><label for=\"iconPlusMinus-10\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-10 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#2_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7_%D9%88_%DA%AF%D9%88%D8%A7%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%DB%8C%D9%81%DB%8C%D8%AA_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" title=\"2. \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0639\u062a\u0628\u0631 \u0628\u0631\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0686\u06cc\u0633\u062a\u061f\">2. \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0639\u062a\u0628\u0631 \u0628\u0631\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-11\"\/><label for=\"iconPlusMinus-11\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-11 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#3_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D8%A7%D8%B2_%D9%81%D8%B1%D8%A2%DB%8C%D9%86%D8%AF_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D9%85%D8%B7%D9%85%D8%A6%D9%86_%D8%A7%D8%B7%D9%85%DB%8C%D9%86%D8%A7%D9%86_%D8%AD%D8%A7%D8%B5%D9%84_%DA%A9%D8%B1%D8%AF_%D9%88_%D8%B1%DB%8C%D8%B3%DA%A9%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%B1%D8%AA%D8%A8%D8%B7_%D8%A8%D8%A7_%D8%AD%D9%85%D9%84_%D9%88_%D8%AA%D8%B1%D8%AE%DB%8C%D8%B5_%DA%AF%D9%85%D8%B1%DA%A9%DB%8C_%D8%B1%D8%A7_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%A7%D8%AF%D8%9F\" title=\"3. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u0637\u0645\u0626\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u0648 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0645\u0644 \u0648 \u062a\u0631\u062e\u06cc\u0635 \u06af\u0645\u0631\u06a9\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f\u061f\">3. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u0637\u0645\u0626\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u0648 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0645\u0644 \u0648 \u062a\u0631\u062e\u06cc\u0635 \u06af\u0645\u0631\u06a9\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f\u061f<\/a><\/li><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-12\"\/><label for=\"iconPlusMinus-12\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-12 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#4_%DA%86%D9%87_%D9%86%DA%A9%D8%A7%D8%AA%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D9%87%D8%B4_%D8%B6%D8%A7%DB%8C%D8%B9%D8%A7%D8%AA_%D9%88_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A8%D9%87%D8%B1%D9%87%E2%80%8C%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" title=\"4. \u0686\u0647 \u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061f\">4. \u0686\u0647 \u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061f<\/a><\/li><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-13\"\/><label for=\"iconPlusMinus-13\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-13 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#5_%D9%82%DB%8C%D9%85%D8%AA_%D9%88_%D9%86%D9%88%D8%B3%D8%A7%D9%86%D8%A7%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%A8%D8%B1_%D8%AA%D8%B5%D9%85%DB%8C%D9%85%D8%A7%D8%AA_%D8%AA%D8%A3%D9%85%DB%8C%D9%86_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D8%AA%D8%A3%D8%AB%DB%8C%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%AF%D8%9F\" title=\"5. \u0642\u06cc\u0645\u062a \u0648 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u0627\u0632\u0627\u0631 \u0686\u06af\u0648\u0646\u0647 \u0628\u0631 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u062a\u0623\u0645\u06cc\u0646 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062a\u0623\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f\u061f\">5. \u0642\u06cc\u0645\u062a \u0648 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u0627\u0632\u0627\u0631 \u0686\u06af\u0648\u0646\u0647 \u0628\u0631 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u062a\u0623\u0645\u06cc\u0646 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062a\u0623\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f\u061f<\/a><\/li><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-14\"\/><label for=\"iconPlusMinus-14\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-14 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#6_%D8%A2%DB%8C%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%AA%D8%A3%D9%85%DB%8C%D9%86%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1_%D9%88%D8%A7%D9%82%D8%B9%D8%A7%D9%8B_%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\" title=\"6. \u0622\u06cc\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0648\u0627\u0642\u0639\u0627\u064b \u062a\u0641\u0627\u0648\u062a \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f\">6. \u0622\u06cc\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0648\u0627\u0642\u0639\u0627\u064b \u062a\u0641\u0627\u0648\u062a \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<\/a><\/li><style>#vir-st-container ul li a.vir-st-heading-level-2 {color: #f5f6f6!important;}<\/style><li class='vir-st-page-1 vir-st-heading-level-2' style='font-size: 16px!important;font-weight: 400!important;'><input type=\"checkbox\" id=\"iconPlusMinus-15\"\/><label for=\"iconPlusMinus-15\"><svg id=\"iconPlus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M256 80c0-17.7-14.3-32-32-32s-32 14.3-32 32v144H48c-17.7 0-32 14.3-32 32s14.3 32 32 32h144v144c0 17.7 14.3 32 32 32s32-14.3 32-32V288h144c17.7 0 32-14.3 32-32s-14.3-32-32-32H256V80z\"><\/path><\/svg><svg id=\"iconMinus\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" preserveAspectRatio=\"xMidYMid meet\" viewBox=\"0 0 448 512\"><path d=\"M432 256c0 17.7-14.3 32-32 32H48c-17.7 0-32-14.3-32-32s14.3-32 32-32h352c17.7 0 32 14.3 32 32z\"><\/path><\/svg><\/label><a class=\"vir-st-link vir-st-heading-15 vir-st-heading-level-2\" href=\"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#7_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D8%A7%D8%B7%D9%85%DB%8C%D9%86%D8%A7%D9%86_%D8%AD%D8%A7%D8%B5%D9%84_%DA%A9%D8%B1%D8%AF_%DA%A9%D9%87_%D9%85%D8%AD%D8%B5%D9%88%D9%84_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%85%D8%AD%DB%8C%D8%B7_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D9%88_%D8%AA%D8%AC%D9%87%DB%8C%D8%B2%D8%A7%D8%AA_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87_%D8%B3%D8%A7%D8%B2%DA%AF%D8%A7%D8%B1_%D8%A7%D8%B3%D8%AA%D8%9F\" title=\"7. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644 \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0628\u0627 \u0645\u062d\u06cc\u0637 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0633\u0627\u0632\u06af\u0627\u0631 \u0627\u0633\u062a\u061f\">7. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644 \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0628\u0627 \u0645\u062d\u06cc\u0637 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0633\u0627\u0632\u06af\u0627\u0631 \u0627\u0633\u062a\u061f<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"vir-st-section\" id=\"%D8%A7%D8%B4%D8%AA%D8%A8%D8%A7%D9%87%D8%A7%D8%AA_%D8%B1%D8%A7%DB%8C%D8%AC_%D8%AF%D8%B1_%D8%AA%D8%A3%D9%85%DB%8C%D9%86_%D8%B5%D9%86%D8%B9%D8%AA%DB%8C\"><\/span>\u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a \u0631\u0627\u06cc\u062c \u062f\u0631 \u062a\u0623\u0645\u06cc\u0646 \u0635\u0646\u0639\u062a\u06cc<span class=\"vir-st-section-end\"><\/span><\/h2>\n<p>\u062a\u062c\u0631\u0628\u0647 \u0645\u0627 \u062f\u0631 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0647 \u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a\u06cc \u062f\u0686\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f:<\/p>\n<h3><span class=\"vir-st-section\" id=\"%DB%B1_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D9%86%D9%88%D8%B9_%D9%86%D8%A7%D9%85%D9%86%D8%A7%D8%B3%D8%A8_%D9%BE%D9%84%DB%8C%D9%85%D8%B1\"><\/span>\u06f1. \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u067e\u0644\u06cc\u0645\u0631<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062f\u0631 \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0646\u0633\u0628\u062a \u0645\u0648\u0646\u0648\u0645\u0631\u0647\u0627 \u062f\u0631 \u062e\u0648\u0627\u0635 \u0646\u0647\u0627\u06cc\u06cc \u062a\u0627\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0627\u0631\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0627\u062f\u0631\u0633\u062a \u0646\u0648\u0639 \u067e\u0644\u06cc\u0645\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc\u060c \u0645\u0642\u0627\u0648\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0631\u0648\u063a\u0646\u200c\u0647\u0627 \u0648 \u062e\u0631\u0627\u0628\u06cc \u0633\u0631\u06cc\u0639 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0634\u0648\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u062a\u062c\u0631\u0628\u0647 \u062f\u0627\u0631\u06cc\u0645 \u06a9\u0647 \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642 \u0646\u06cc\u0627\u0632 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u06cc\u0646\u0647 \u067e\u0644\u06cc\u0645\u0631 \u0648 \u06a9\u0627\u0647\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"%DB%B2_%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%AC%D9%87_%D8%A8%D9%87_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7%DB%8C_%D8%A8%DB%8C%D9%86%E2%80%8C%D8%A7%D9%84%D9%85%D9%84%D9%84%DB%8C\"><\/span>\u06f2. \u0639\u062f\u0645 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0645\u0648\u0627\u062f \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0628\u0627\u06cc\u062f \u0645\u0637\u0627\u0628\u0642 \u0628\u0627 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc <strong>ASTM\u060c ISO \u0648 DIN<\/strong> \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f \u062a\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0648 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0622\u0646\u0647\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0634\u0648\u062f. \u0639\u062f\u0645 \u0628\u0631\u0631\u0633\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u062e\u0631\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u067e\u0627\u06cc\u06cc\u0646\u060c \u0645\u0642\u0627\u0648\u0645\u062a \u0646\u0627\u06a9\u0627\u0641\u06cc \u06cc\u0627 \u0627\u0628\u0639\u0627\u062f \u063a\u06cc\u0631 \u062f\u0642\u06cc\u0642 \u0645\u0646\u062c\u0631 \u0634\u0648\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"%DB%B3_%D8%AA%D8%A3%D9%85%DB%8C%D9%86%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D8%BA%DB%8C%D8%B1%D9%82%D8%A7%D8%A8%D9%84_%D8%A7%D8%B9%D8%AA%D9%85%D8%A7%D8%AF\"><\/span>\u06f3. \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0646\u0627\u0633\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0645\u0648\u0641\u0642\u06cc\u062a \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0627\u0633\u062a. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0641\u0631\u0648\u0634\u0646\u062f\u06af\u0627\u0646 \u0628\u062f\u0648\u0646 \u0633\u0627\u0628\u0642\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0634\u06a9\u0644\u0627\u062a \u0632\u06cc\u0631 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f:<\/p>\n<ul>\n<li>\u062a\u062d\u0648\u06cc\u0644 \u062f\u06cc\u0631\u0647\u0646\u06af\u0627\u0645 \u0648 \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u062e\u0637 \u062a\u0648\u0644\u06cc\u062f<\/li>\n<li>\u0646\u0648\u0633\u0627\u0646 \u0642\u06cc\u0645\u062a \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627<\/li>\n<li>\u06a9\u06cc\u0641\u06cc\u062a \u0646\u0627\u0645\u0634\u062e\u0635 \u0648 \u06a9\u0627\u0647\u0634 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a<\/li>\n<\/ul>\n<p>\u0645\u0627 \u062f\u0631 MT Royal\u060c \u0628\u0627 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u0639\u062a\u0628\u0631 \u062c\u0647\u0627\u0646\u06cc\u060c \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645 \u06a9\u0647 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0623\u0645\u06cc\u0646 \u0634\u0641\u0627\u0641 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f.<\/p>\n<hr \/>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-45779\" src=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-1.jpg\" alt=\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\" width=\"1280\" height=\"720\" srcset=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-1.jpg 1280w, https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-1-300x169.jpg 300w, https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-1-1024x576.jpg 1024w, https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-1-600x338.jpg 600w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/h2>\n<h2><span class=\"vir-st-section\" id=\"%D9%85%D9%82%D8%A7%DB%8C%D8%B3%D9%87%E2%80%8C%D9%87%D8%A7_%D9%88_%D9%86%DA%A9%D8%A7%D8%AA_%D8%B5%D9%86%D8%B9%D8%AA%DB%8C_%D9%88%DB%8C%DA%98%D9%87\"><\/span>\u0645\u0642\u0627\u06cc\u0633\u0647\u200c\u0647\u0627 \u0648 \u0646\u06a9\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648\u06cc\u0698\u0647<span class=\"vir-st-section-end\"><\/span><\/h2>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u060c \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u06cc \u0627\u0646\u0648\u0627\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0648 \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0622\u0646\u0647\u0627 \u0627\u0647\u0645\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u062f:<\/p>\n<ul>\n<li><strong>NBR \u0645\u0639\u0645\u0648\u0644\u06cc (Standard NBR):<\/strong> \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0648 \u0645\u0642\u0627\u0648\u0645 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0631\u0648\u063a\u0646\u200c\u0647\u0627\u06cc \u0633\u0628\u06a9\u060c \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0634\u06cc\u0644\u0646\u06af\u200c\u0647\u0627 \u0648 \u0648\u0627\u0634\u0631\u0647\u0627.<\/li>\n<li><strong>NBR \u0645\u0642\u0627\u0648\u0645 \u0628\u0647 \u062d\u0631\u0627\u0631\u062a (Heat Resistant NBR):<\/strong> \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062f\u0631 \u062f\u0645\u0627\u0647\u0627\u06cc \u0628\u0627\u0644\u0627\u060c \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0642\u0637\u0639\u0627\u062a \u062e\u0648\u062f\u0631\u0648 \u0648 \u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0635\u0646\u0639\u062a\u06cc.<\/li>\n<li><strong>HNBR (Hydrogenated NBR):<\/strong> \u0645\u0642\u0627\u0648\u0645 \u0628\u0647 \u0627\u06a9\u0633\u06cc\u062f\u0627\u0633\u06cc\u0648\u0646 \u0648 \u0633\u0627\u06cc\u0634\u060c \u06af\u0632\u06cc\u0646\u0647 \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0642\u0637\u0639\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0628\u0627 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627.<\/li>\n<\/ul>\n<p>\u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u0633\u0627\u0633 \u0645\u062d\u06cc\u0637 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0647\u0627\u06cc\u06cc\u060c \u0646\u0648\u0639 \u0645\u0646\u0627\u0633\u0628 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u0646\u062f \u062a\u0627 \u0647\u0645 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f \u0648 \u0647\u0645 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/p>\n<hr \/>\n<h2><span class=\"vir-st-section\" id=\"%D9%86%DA%A9%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C_%D8%AF%D8%B1_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D9%88_%D8%B2%D9%86%D8%AC%DB%8C%D8%B1%D9%87_%D8%AA%D8%A3%D9%85%DB%8C%D9%86\"><\/span>\u0646\u06a9\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0632\u0646\u062c\u06cc\u0631\u0647 \u062a\u0623\u0645\u06cc\u0646<span class=\"vir-st-section-end\"><\/span><\/h2>\n<p>\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0634\u0627\u0645\u0644 \u0645\u0631\u0627\u062d\u0644 \u0641\u0646\u06cc \u0648 \u0644\u062c\u0633\u062a\u06cc\u06a9\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0645\u0648\u0641\u0642\u06cc\u062a \u067e\u0631\u0648\u0698\u0647 \u0631\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f:<\/p>\n<ol>\n<li><strong>\u0628\u0631\u0631\u0633\u06cc \u062a\u0627\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc:<\/strong> \u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u0639\u062a\u0628\u0631 \u0628\u0627 \u0633\u0627\u0628\u0642\u0647 \u062a\u0636\u0645\u06cc\u0646 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u062a\u062d\u0648\u06cc\u0644 \u0628\u0647 \u0645\u0648\u0642\u0639.<\/li>\n<li><strong>\u06a9\u0646\u062a\u0631\u0644 \u06a9\u06cc\u0641\u06cc\u062a \u0642\u0628\u0644 \u0627\u0632 \u062d\u0645\u0644:<\/strong> \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0628\u0631\u0627\u06cc \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u0645\u0637\u0627\u0628\u0642\u062a \u0628\u0627 \u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc.<\/li>\n<li><strong>\u0645\u0633\u062a\u0646\u062f\u0633\u0627\u0632\u06cc \u0648 \u06af\u0645\u0631\u06a9:<\/strong> \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u0627\u0632 \u0631\u0639\u0627\u06cc\u062a \u0642\u0648\u0627\u0646\u06cc\u0646 \u0648\u0627\u0631\u062f\u0627\u062a\u060c \u0635\u062f\u0648\u0631 \u0627\u0633\u0646\u0627\u062f \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0648 \u06a9\u0627\u0647\u0634 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u06af\u0645\u0631\u06a9\u06cc.<\/li>\n<\/ol>\n<p>\u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u062a\u062c\u0631\u0628\u0647 \u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a\u060c \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0645\u0631\u0627\u062d\u0644 \u0631\u0627 \u0628\u0627 \u062f\u0642\u062a \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062f\u063a\u062f\u063a\u0647\u200c\u0627\u06cc \u0627\u0632 \u0628\u0627\u0628\u062a \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0632\u0645\u0627\u0646 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<hr \/>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-45780 size-full\" src=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.png\" alt=\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\" width=\"512\" height=\"512\" srcset=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.png 512w, https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-300x300.png 300w, https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/h2>\n<h2><span class=\"vir-st-section\" id=\"%D9%BE%D8%B1%D8%B3%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%BE%D8%B1%D8%AA%DA%A9%D8%B1%D8%A7%D8%B1_%D9%85%D8%AF%DB%8C%D8%B1%D8%A7%D9%86_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87%E2%80%8C%D9%87%D8%A7\"><\/span>\u067e\u0631\u0633\u0634\u200c\u0647\u0627\u06cc \u067e\u0631\u062a\u06a9\u0631\u0627\u0631 \u0645\u062f\u06cc\u0631\u0627\u0646 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627<span class=\"vir-st-section-end\"><\/span><\/h2>\n<p>\u062a\u062c\u0631\u0628\u0647 \u0645\u0627 \u062f\u0631 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0648 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0645\u062f\u06cc\u0631\u0627\u0646 \u0648 \u0645\u0633\u0626\u0648\u0644\u0627\u0646 \u062e\u0631\u06cc\u062f \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u062a\u0623\u0645\u06cc\u0646 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u0633\u0624\u0627\u0644\u0627\u062a \u0648 \u062f\u063a\u062f\u063a\u0647\u200c\u0647\u0627\u06cc \u0645\u0634\u062a\u0631\u06a9\u06cc \u0645\u0648\u0627\u062c\u0647 \u0647\u0633\u062a\u0646\u062f. \u0634\u0646\u0627\u062e\u062a \u062f\u0642\u06cc\u0642 \u0627\u06cc\u0646 \u067e\u0631\u0633\u0634\u200c\u0647\u0627 \u0648 \u0627\u0631\u0627\u0626\u0647 \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u062a\u062e\u0635\u0635\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0628\u0647\u062a\u0631\u06cc \u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0623\u0645\u06cc\u0646 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0627\u062a\u062e\u0627\u0630 \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0628\u0631\u062e\u06cc \u0627\u0632 \u067e\u0631\u062a\u06a9\u0631\u0627\u0631\u062a\u0631\u06cc\u0646 \u067e\u0631\u0633\u0634\u200c\u0647\u0627 \u0648 \u067e\u0627\u0633\u062e\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0622\u0646\u0647\u0627 \u067e\u0631\u062f\u0627\u062e\u062a\u0647\u200c\u0627\u06cc\u0645:<\/p>\n<h3><span class=\"vir-st-section\" id=\"1_%DA%86%D9%87_%D8%AA%D9%81%D8%A7%D9%88%D8%AA%DB%8C_%D8%A8%DB%8C%D9%86_%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D9%85%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF_%D9%88_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D9%85%D9%86%D8%A7%D8%B3%D8%A8%E2%80%8C%D8%AA%D8%B1%DB%8C%D9%86_%D9%86%D9%88%D8%B9_%D8%B1%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%DA%A9%D8%B1%D8%AF%D8%9F\"><\/span>1. \u0686\u0647 \u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u0648 \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0646\u0648\u0639 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0628\u0647 \u0635\u0648\u0631\u062a \u06af\u0631\u06cc\u062f\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0635\u06cc \u062f\u0627\u0631\u0646\u062f. \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0634\u0627\u0645\u0644 \u0645\u06cc\u0632\u0627\u0646 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644\u060c \u062f\u0631\u0635\u062f \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\u060c \u062f\u0627\u0646\u0633\u06cc\u062a\u0647\u060c \u0648\u06cc\u0633\u06a9\u0648\u0632\u06cc\u062a\u0647 \u0648 \u0645\u0642\u0627\u0648\u0645\u062a \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0627\u0633\u062a. \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0645\u0646\u0627\u0633\u0628 \u0628\u0627\u06cc\u062f \u0628\u0631 \u0627\u0633\u0627\u0633 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u060c \u0646\u0648\u0639 \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0645\u062d\u06cc\u0637\u06cc \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0642\u0637\u0639\u0627\u062a \u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0639\u0631\u0636 \u062f\u0645\u0627 \u0648 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0634\u062f\u06cc\u062f \u0647\u0633\u062a\u0646\u062f\u060c \u06af\u0631\u06cc\u062f\u06cc \u0628\u0627 \u0645\u0642\u0627\u0648\u0645\u062a \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0627\u0644\u0627 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0647\u062a\u0631 \u062a\u0631\u062c\u06cc\u062d \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u0645\u0634\u0627\u0648\u0631\u0647 \u062a\u062e\u0635\u0635\u06cc\u060c \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u0645\u0646\u0627\u0633\u0628\u200c\u062a\u0631\u06cc\u0646 \u0646\u0648\u0639 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0648\u062f \u0648 \u0631\u06cc\u0633\u06a9 \u062e\u0637\u0627 \u0648 \u0636\u0627\u06cc\u0639\u0627\u062a \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"2_%D8%A7%D8%B3%D8%AA%D8%A7%D9%86%D8%AF%D8%A7%D8%B1%D8%AF%D9%87%D8%A7_%D9%88_%DA%AF%D9%88%D8%A7%D9%87%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%DA%A9%DB%8C%D9%81%DB%8C%D8%AA_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span>2. \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0639\u062a\u0628\u0631 \u0628\u0631\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0686\u06cc\u0633\u062a\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0627\u06cc\u062f \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0628\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0627\u0646\u0646\u062f ASTM\u060c ISO \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0648\u06cc\u0698\u0647 \u0635\u0646\u0639\u062a \u0644\u0627\u0633\u062a\u06cc\u06a9 \u062a\u0648\u062c\u0647 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644 \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0645\u0637\u0627\u0628\u0642 \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0645\u0648\u0631\u062f \u0627\u0646\u062a\u0638\u0627\u0631 \u0634\u0645\u0627 \u0627\u0633\u062a \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0633\u062e\u062a \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u0646\u0627\u0633\u0628\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0646\u062f\u0627\u0634\u062a\u0646 \u0627\u06cc\u0646 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u062e\u0631\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u06cc \u0634\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0639\u0645\u0644 \u06a9\u06cc\u0641\u06cc\u062a \u0644\u0627\u0632\u0645 \u0631\u0627 \u0646\u062f\u0627\u0631\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u062a\u0645\u0627\u0645\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0631\u0627 \u0627\u0632 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u0639\u062a\u0628\u0631 \u062c\u0647\u0627\u0646\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0648 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u06af\u0648\u0627\u0647\u06cc\u200c\u0647\u0627 \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u0647\u0645\u0631\u0627\u0647 \u0645\u062d\u0635\u0648\u0644 \u0627\u0631\u0627\u0626\u0647 \u0634\u0648\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"3_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D8%A7%D8%B2_%D9%81%D8%B1%D8%A2%DB%8C%D9%86%D8%AF_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA_%D9%85%D8%B7%D9%85%D8%A6%D9%86_%D8%A7%D8%B7%D9%85%DB%8C%D9%86%D8%A7%D9%86_%D8%AD%D8%A7%D8%B5%D9%84_%DA%A9%D8%B1%D8%AF_%D9%88_%D8%B1%DB%8C%D8%B3%DA%A9%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%B1%D8%AA%D8%A8%D8%B7_%D8%A8%D8%A7_%D8%AD%D9%85%D9%84_%D9%88_%D8%AA%D8%B1%D8%AE%DB%8C%D8%B5_%DA%AF%D9%85%D8%B1%DA%A9%DB%8C_%D8%B1%D8%A7_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%A7%D8%AF%D8%9F\"><\/span>3. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u0637\u0645\u0626\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u0648 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0645\u0644 \u0648 \u062a\u0631\u062e\u06cc\u0635 \u06af\u0645\u0631\u06a9\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u062f\u0627\u0646\u0634 \u0648 \u062a\u062c\u0631\u0628\u0647 \u062f\u0631 \u0645\u062f\u06cc\u0631\u06cc\u062a \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644\u060c \u062a\u0631\u062e\u06cc\u0635 \u06af\u0645\u0631\u06a9\u06cc\u060c \u0631\u0639\u0627\u06cc\u062a \u0645\u0642\u0631\u0631\u0627\u062a \u0627\u06cc\u0645\u0646\u06cc \u0648 \u0628\u0633\u062a\u0647\u200c\u0628\u0646\u062f\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0633\u062a. \u062a\u0623\u062e\u06cc\u0631 \u062f\u0631 \u062a\u0631\u062e\u06cc\u0635 \u06cc\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u062a\u0648\u0642\u0641 \u062e\u0637\u0648\u0637 \u062a\u0648\u0644\u06cc\u062f \u0634\u0648\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u062a\u062c\u0631\u0628\u0647 \u06af\u0633\u062a\u0631\u062f\u0647 \u062f\u0631 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc\u060c \u0627\u0632 \u0645\u0631\u062d\u0644\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u062a\u0627 \u062a\u062d\u0648\u06cc\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644 \u062f\u0631 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u060c \u0647\u0645\u0647 \u0645\u0631\u0627\u062d\u0644 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0646\u062a\u0631\u0644\u200c\u0634\u062f\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0648 \u0628\u0647 \u0634\u0645\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645 \u06a9\u0647 \u0628\u062f\u0648\u0646 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0632 \u062a\u0623\u062e\u06cc\u0631 \u06cc\u0627 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u06af\u0645\u0631\u06a9\u06cc\u060c \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"4_%DA%86%D9%87_%D9%86%DA%A9%D8%A7%D8%AA%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%DA%A9%D8%A7%D9%87%D8%B4_%D8%B6%D8%A7%DB%8C%D8%B9%D8%A7%D8%AA_%D9%88_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%A8%D9%87%D8%B1%D9%87%E2%80%8C%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D9%88%D8%AC%D9%88%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>4. \u0686\u0647 \u0646\u06a9\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0645\u062f\u06cc\u0631\u06cc\u062a \u062f\u0642\u06cc\u0642 \u062f\u0645\u0627\u060c \u0631\u0637\u0648\u0628\u062a \u0648 \u0634\u0631\u0627\u06cc\u0637 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0627\u0633\u062a. \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0646\u0627\u062f\u0631\u0633\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0631 \u0648\u06cc\u0633\u06a9\u0648\u0632\u06cc\u062a\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062a\u0631\u06a9\u06cc\u0628 \u0627\u0634\u062a\u0628\u0627\u0647 \u0628\u0627 \u062f\u06cc\u06af\u0631 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062e\u0648\u0627\u0635 \u0646\u0647\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0645\u0634\u0627\u0648\u0631\u0647 \u0641\u0646\u06cc\u060c \u0628\u0647 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u06cc\u0646\u0647 \u06a9\u0646\u0646\u062f\u060c \u0636\u0627\u06cc\u0639\u0627\u062a \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u0646\u062f \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0646\u0647\u0627\u06cc\u06cc \u0631\u0627 \u0627\u0631\u062a\u0642\u0627\u0621 \u062f\u0647\u0646\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"5_%D9%82%DB%8C%D9%85%D8%AA_%D9%88_%D9%86%D9%88%D8%B3%D8%A7%D9%86%D8%A7%D8%AA_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D8%A8%D8%B1_%D8%AA%D8%B5%D9%85%DB%8C%D9%85%D8%A7%D8%AA_%D8%AA%D8%A3%D9%85%DB%8C%D9%86_%D8%A2%DA%A9%D8%B1%DB%8C%D9%84%D9%88%D9%86%DB%8C%D8%AA%D8%B1%DB%8C%D9%84_%D8%A8%D9%88%D8%AA%D8%A7%D8%AF%DB%8C%D9%86_%D8%AA%D8%A3%D8%AB%DB%8C%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>5. \u0642\u06cc\u0645\u062a \u0648 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u0627\u0632\u0627\u0631 \u0686\u06af\u0648\u0646\u0647 \u0628\u0631 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u062a\u0623\u0645\u06cc\u0646 \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062a\u0623\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0642\u06cc\u0645\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u062c\u0647\u0627\u0646\u06cc \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0627\u0631\u0632\u060c \u0639\u0631\u0636\u0647 \u0648 \u062a\u0642\u0627\u0636\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc\u060c \u0648 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f. \u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u0642\u06cc\u0645\u062a \u0648 \u0632\u0645\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u062f\u0631 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0631\u0648\u0646\u062f\u0647\u0627\u06cc \u0628\u0627\u0632\u0627\u0631 \u0648 \u0627\u0631\u0627\u0626\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u062a\u0623\u0645\u06cc\u0646\u060c \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0628\u0647\u06cc\u0646\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u062a\u062e\u0627\u0630 \u0634\u0648\u062f \u0648 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"6_%D8%A2%DB%8C%D8%A7_%D8%A7%D9%86%D8%AA%D8%AE%D8%A7%D8%A8_%D8%AA%D8%A3%D9%85%DB%8C%D9%86%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%85%D8%B9%D8%AA%D8%A8%D8%B1_%D9%88%D8%A7%D9%82%D8%B9%D8%A7%D9%8B_%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%A7%DB%8C%D8%AC%D8%A7%D8%AF_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\"><\/span>6. \u0622\u06cc\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0648\u0627\u0642\u0639\u0627\u064b \u062a\u0641\u0627\u0648\u062a \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0628\u0644\u0647\u060c \u062a\u062c\u0631\u0628\u0647 \u0645\u0627 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0641\u0627\u0648\u062a \u0628\u06cc\u0646 \u062e\u0631\u06cc\u062f \u0627\u0632 \u06cc\u06a9 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0648 \u06cc\u06a9 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u0646\u0627\u0634\u0646\u0627\u0633\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0627\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644\u060c \u0632\u0645\u0627\u0646 \u062a\u062d\u0648\u06cc\u0644 \u0648 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u06cc\u06a9 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u0631\u0627\u0626\u0647 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a\u060c \u0645\u0634\u0627\u0648\u0631\u0647 \u0641\u0646\u06cc\u060c \u062e\u062f\u0645\u0627\u062a \u067e\u0633 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0641\u0631\u0622\u06cc\u0646\u062f \u0648\u0627\u0631\u062f\u0627\u062a \u0631\u0627 \u0646\u06cc\u0632 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647\u200c\u0627\u06cc \u0628\u0627 \u0633\u0627\u0628\u0642\u0647\u060c \u0627\u06cc\u0646 \u062e\u062f\u0645\u0627\u062a \u0631\u0627 \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u062e\u0627\u0635 \u0647\u0631 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0648 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0632\u0646\u062c\u06cc\u0631\u0647 \u062a\u0623\u0645\u06cc\u0646 \u0634\u0645\u0627 \u0628\u062f\u0648\u0646 \u0648\u0642\u0641\u0647 \u0648 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0639\u0627\u0644\u06cc \u0627\u062f\u0627\u0645\u0647 \u06cc\u0627\u0628\u062f.<\/p>\n<h3><span class=\"vir-st-section\" id=\"7_%DA%86%DA%AF%D9%88%D9%86%D9%87_%D9%85%DB%8C%E2%80%8C%D8%AA%D9%88%D8%A7%D9%86_%D8%A7%D8%B7%D9%85%DB%8C%D9%86%D8%A7%D9%86_%D8%AD%D8%A7%D8%B5%D9%84_%DA%A9%D8%B1%D8%AF_%DA%A9%D9%87_%D9%85%D8%AD%D8%B5%D9%88%D9%84_%D9%88%D8%A7%D8%B1%D8%AF%D8%A7%D8%AA%DB%8C_%D8%A8%D8%A7_%D9%85%D8%AD%DB%8C%D8%B7_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D9%88_%D8%AA%D8%AC%D9%87%DB%8C%D8%B2%D8%A7%D8%AA_%DA%A9%D8%A7%D8%B1%D8%AE%D8%A7%D9%86%D9%87_%D8%B3%D8%A7%D8%B2%DA%AF%D8%A7%D8%B1_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>7. \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062d\u0627\u0635\u0644 \u06a9\u0631\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644 \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0628\u0627 \u0645\u062d\u06cc\u0637 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0633\u0627\u0632\u06af\u0627\u0631 \u0627\u0633\u062a\u061f<span class=\"vir-st-section-end\"><\/span><\/h3>\n<p>\u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0648 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u06a9\u0627\u062a \u062d\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a. \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062c\u0632\u0626\u06cc \u062f\u0631 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u06cc\u0627 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u0627\u062f\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u062d\u0635\u0648\u0644 \u0646\u0647\u0627\u06cc\u06cc \u0627\u062b\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f. \u0645\u0627 \u062f\u0631 MT Royal \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u062f\u0642\u06cc\u0642 \u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc \u0648 \u0627\u0631\u0627\u0626\u0647 \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0622\u0632\u0645\u0627\u06cc\u0634\u06cc\u060c \u0627\u0645\u06a9\u0627\u0646 \u062a\u0633\u062a \u0648 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0642\u0628\u0644 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0639\u0645\u062f\u0647 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0627 \u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u06a9\u0627\u0645\u0644 \u062a\u0635\u0645\u06cc\u0645 \u0628\u06af\u06cc\u0631\u0646\u062f.<\/p>\n<hr \/>\n<h2><span class=\"vir-st-section\" id=\"%D8%AC%D9%85%D8%B9%E2%80%8C%D8%A8%D9%86%D8%AF%DB%8C\"><\/span>\u062c\u0645\u0639\u200c\u0628\u0646\u062f\u06cc<span class=\"vir-st-section-end\"><\/span><\/h2>\n<p>\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\u060c \u06cc\u06a9 \u0641\u0631\u0635\u062a \u06a9\u0644\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0633\u062a \u062a\u0627 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u062a\u0631\u060c \u062f\u0648\u0627\u0645 \u0628\u06cc\u0634\u062a\u0631 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0645\u062a\u0631 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0635\u062d\u06cc\u062d \u0646\u0648\u0639 \u067e\u0644\u06cc\u0645\u0631\u060c \u0631\u0639\u0627\u06cc\u062a \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 \u0645\u0627\u0646\u0646\u062f <strong>MT Royal<\/strong> \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647 \u0634\u0645\u0627 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u0622\u0631\u0627\u0645\u0634 \u062e\u0627\u0637\u0631 \u0648 \u0628\u0647\u06cc\u0646\u0647\u200c\u062a\u0631\u06cc\u0646 \u0634\u06a9\u0644 \u0645\u0645\u06a9\u0646 \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u0631\u0627 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u062f. \u062a\u062c\u0631\u0628\u0647 \u0645\u0627 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0646\u06a9\u0627\u062a \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0646\u0647 \u062a\u0646\u0647\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u0628\u0644\u06a9\u0647 \u0631\u0636\u0627\u06cc\u062a \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062e\u0637\u0648\u0637 \u062a\u0648\u0644\u06cc\u062f \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0647 \u062d\u062f\u0627\u06a9\u062b\u0631 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0627\u0645\u0631\u0648\u0632 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u062a\u0648\u0644\u06cc\u062f \u0644\u0627\u0633\u062a\u06cc\u06a9\u060c \u062a\u0648\u062c\u0647 \u0628\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u062f\u06cc\u06af\u0631 \u06cc\u06a9 \u06af\u0632\u06cc\u0646\u0647 \u0646\u06cc\u0633\u062a\u061b \u0628\u0644\u06a9\u0647 \u06cc\u06a9 \u0636\u0631\u0648\u0631\u062a \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0627\u0633\u062a. \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0646\u0647 \u062a\u0646\u0647\u0627 \u062a\u0623\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645\u06cc \u0628\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f \u0646\u0647\u0627\u06cc\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062f\u0627\u0631\u062f\u060c \u0628\u0644\u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0639\u06cc\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u06cc\u0632\u0627\u0646 \u062f\u0648\u0627\u0645\u060c \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0648 \u062d\u062a\u06cc \u0627\u06cc\u0645\u0646\u06cc \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0646\u0647\u0627\u06cc\u06cc \u0628\u0627\u0634\u062f. \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 (Acrylonitrile Butadiene) \u0628\u0647&#8230;<\/p>\n","protected":false},"author":1,"featured_media":45777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[4096],"tags":[],"class_list":["post-32280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4096"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644<\/title>\n<meta name=\"description\" content=\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mtroyal.com.tr\/fa\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\" \/>\n<meta property=\"og:description\" content=\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mtroyal.com.tr\/fa\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T11:01:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0645\u062f\u06cc\u0631\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u062f\u06cc\u0631\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/\"},\"author\":{\"name\":\"\u0645\u062f\u06cc\u0631\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/person\\\/7dfa8de9bdb4b74d73eb9a11ff82d3cf\"},\"headline\":\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\",\"datePublished\":\"2025-12-01T11:01:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/\"},\"wordCount\":43,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg\",\"articleSection\":[\"\u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/\",\"name\":\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg\",\"datePublished\":\"2025-12-01T11:01:07+00:00\",\"description\":\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg\",\"contentUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\",\"name\":\"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\",\"description\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a\",\"publisher\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#organization\",\"name\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"width\":192,\"height\":28,\"caption\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647\"},\"image\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/person\\\/7dfa8de9bdb4b74d73eb9a11ff82d3cf\",\"name\":\"\u0645\u062f\u06cc\u0631\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/litespeed\\\/avatar\\\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/litespeed\\\/avatar\\\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885\",\"contentUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/litespeed\\\/avatar\\\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885\",\"caption\":\"\u0645\u062f\u06cc\u0631\"},\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/author\\\/admin\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","description":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mtroyal.com.tr\/fa\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646","og_description":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.","og_url":"https:\/\/mtroyal.com.tr\/fa\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646\/","og_site_name":"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","article_published_time":"2025-12-01T11:01:07+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg","type":"image\/jpeg"}],"author":"\u0645\u062f\u06cc\u0631","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"\u0645\u062f\u06cc\u0631"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#article","isPartOf":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/"},"author":{"name":"\u0645\u062f\u06cc\u0631","@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/person\/7dfa8de9bdb4b74d73eb9a11ff82d3cf"},"headline":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646","datePublished":"2025-12-01T11:01:07+00:00","mainEntityOfPage":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/"},"wordCount":43,"commentCount":0,"publisher":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#organization"},"image":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#primaryimage"},"thumbnailUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg","articleSection":["\u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/","url":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/","name":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","isPartOf":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#primaryimage"},"image":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#primaryimage"},"thumbnailUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg","datePublished":"2025-12-01T11:01:07+00:00","description":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646 \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646\u061b \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u0648\u0639 \u0635\u062d\u06cc\u062d\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u062a\u0623\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0645\u0639\u062a\u0628\u0631 MT Royal.","breadcrumb":{"@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#primaryimage","url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg","contentUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/02\/\u0648\u0627\u0631\u062f\u0627\u062a-\u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644-\u0628\u0648\u062a\u0627\u062f\u06cc\u0646.jpg","width":1000,"height":1000,"caption":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646"},{"@type":"BreadcrumbList","@id":"https:\/\/mtroyal.com.tr\/fa\/%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d8%a2%da%a9%d8%b1%db%8c%d9%84%d9%88%d9%86%db%8c%d8%aa%d8%b1%db%8c%d9%84-%d8%a8%d9%88%d8%aa%d8%a7%d8%af%db%8c%d9%86\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/mtroyal.com.tr\/fa\/"},{"@type":"ListItem","position":2,"name":"\u0648\u0627\u0631\u062f\u0627\u062a \u0622\u06a9\u0631\u06cc\u0644\u0648\u0646\u06cc\u062a\u0631\u06cc\u0644 \u0628\u0648\u062a\u0627\u062f\u06cc\u0646"}]},{"@type":"WebSite","@id":"https:\/\/mtroyal.com.tr\/fa\/#website","url":"https:\/\/mtroyal.com.tr\/fa\/","name":"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","description":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a","publisher":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mtroyal.com.tr\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/mtroyal.com.tr\/fa\/#organization","name":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647","url":"https:\/\/mtroyal.com.tr\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2015\/07\/logo.png","contentUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2015\/07\/logo.png","width":192,"height":28,"caption":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647"},"image":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/person\/7dfa8de9bdb4b74d73eb9a11ff82d3cf","name":"\u0645\u062f\u06cc\u0631","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/litespeed\/avatar\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885","url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/litespeed\/avatar\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885","contentUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/litespeed\/avatar\/e0768f1b78fd789b3ab1a19f9a8a8881.jpg?ver=1784091885","caption":"\u0645\u062f\u06cc\u0631"},"url":"https:\/\/mtroyal.com.tr\/fa\/author\/admin\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/posts\/32280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/comments?post=32280"}],"version-history":[{"count":3,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/posts\/32280\/revisions"}],"predecessor-version":[{"id":45781,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/posts\/32280\/revisions\/45781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/media\/45777"}],"wp:attachment":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/media?parent=32280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/categories?post=32280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/tags?post=32280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}