{"id":39819,"date":"2025-09-16T10:00:57","date_gmt":"2025-09-16T07:00:57","guid":{"rendered":"https:\/\/mtroyal.com.tr\/fa\/?post_type=product&#038;p=39819"},"modified":"2025-07-22T14:19:34","modified_gmt":"2025-07-22T11:19:34","slug":"%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi","status":"publish","type":"product","link":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/","title":{"rendered":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI"},"content":{"rendered":"<p><strong>\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI<\/strong> \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0642\u0627\u0628\u0644\u200c\u0627\u0637\u0645\u06cc\u0646\u0627\u0646 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0635\u0646\u0639\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647\u200c\u0637\u0648\u0631 \u06af\u0633\u062a\u0631\u062f\u0647 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062a\u0648\u0644\u06cc\u062f\u06cc \u0648 \u0635\u0646\u0639\u062a\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0628\u0627 \u0642\u0627\u0628\u0644\u06cc\u062a \u062a\u062d\u0645\u0644 \u0628\u0627\u0631\u0647\u0627\u06cc \u0634\u0639\u0627\u0639\u06cc \u0648 \u0645\u062d\u0648\u0631\u06cc \u0628\u0627\u0644\u0627\u060c \u0637\u0631\u0627\u062d\u06cc \u0645\u0633\u062a\u062d\u06a9\u0645 \u0648 \u0637\u0648\u0644 \u0639\u0645\u0631 \u0632\u06cc\u0627\u062f\u060c \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0648 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0627\u0632 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f \u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u062a\u0627\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u0647 \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0645\u0627\u062f \u062f\u0631 \u062d\u0648\u0632\u0647 \u0628\u06cc\u0632\u0646\u0633 \u0628\u0647 \u0628\u06cc\u0632\u0646\u0633 (B2B)\u060c \u062e\u062f\u0645\u0627\u062a \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0635\u0646\u0639\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0631\u0648\u0632 \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc\u060c \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0648 \u062f\u0648\u0627\u0645 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0633\u062e\u062a \u0648 \u067e\u0631 \u0641\u0634\u0627\u0631 \u062a\u0636\u0645\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u06cc\u06a9 \u0628\u0644\u0628\u0631\u06cc\u0646\u06af \u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u062f\u0648 \u0631\u062f\u06cc\u0641\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0628\u0647 \u062a\u062d\u0645\u0644 \u0628\u0627\u0631\u0647\u0627\u06cc \u0634\u0639\u0627\u0639\u06cc \u0648 \u0645\u062d\u0648\u0631\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0628\u0647\u200c\u0637\u0648\u0631 \u0647\u0645\u0632\u0645\u0627\u0646 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0631\u0646\u062f \u0645\u0639\u062a\u0628\u0631 \u0698\u0627\u067e\u0646\u06cc NACHI \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06a9\u06cc\u0641\u06cc\u062a \u0633\u0627\u062e\u062a \u0628\u0627\u0644\u0627\u060c \u062f\u0642\u062a \u0639\u0645\u0644\u06a9\u0631\u062f \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u062f\u062a\u060c \u0634\u0647\u0631\u062a \u062c\u0647\u0627\u0646\u06cc \u06cc\u0627\u0641\u062a\u0647 \u0627\u0633\u062a. \u0633\u0627\u062e\u062a\u0627\u0631 \u06a9\u0631\u0648\u06cc \u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0628\u0647 \u0622\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u0628\u0627 \u062a\u062d\u0645\u0644 \u0627\u0646\u062d\u0631\u0627\u0641\u0627\u062a \u0632\u0627\u0648\u06cc\u0647\u200c\u0627\u06cc \u0634\u0627\u0641\u062a\u060c \u0639\u0645\u0644\u06a9\u0631\u062f \u0631\u0648\u0627\u0646 \u0648 \u067e\u0627\u06cc\u062f\u0627\u0631 \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0635\u0646\u0639\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0627\u0646\u062a\u062e\u0627\u0628\u06cc \u0645\u0637\u0645\u0626\u0646 \u0628\u0631\u0627\u06cc \u0635\u0646\u0627\u06cc\u0639 \u0641\u0648\u0644\u0627\u062f\u060c \u0645\u0639\u062f\u0646\u060c \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0633\u0646\u06af\u06cc\u0646\u060c \u0646\u0648\u0627\u0631 \u0646\u0642\u0627\u0644\u0647\u200c\u0647\u0627 \u0648 \u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0631\u0627\u0647\u200c\u0633\u0627\u0632\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h2>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627 \u0648 \u0645\u0632\u0627\u06cc\u0627<\/h2>\n<ul>\n<li><strong>\u062a\u062d\u0645\u0644 \u0628\u0627\u0644\u0627\u06cc \u0628\u0627\u0631 \u0634\u0639\u0627\u0639\u06cc \u0648 \u0645\u062d\u0648\u0631\u06cc \u0628\u0647\u200c\u0637\u0648\u0631 \u0647\u0645\u0632\u0645\u0627\u0646<\/strong><br \/>\n\u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u0628\u0627\u0631\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f \u0631\u0627 \u0628\u062f\u0648\u0646 \u0627\u0641\u062a \u06a9\u06cc\u0641\u06cc\u062a \u0639\u0645\u0644\u06a9\u0631\u062f \u062a\u062d\u0645\u0644 \u06a9\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0633\u062e\u062a \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0627\u0633\u062a.<\/li>\n<li><strong>\u0642\u0627\u0628\u0644\u06cc\u062a \u062e\u0648\u062f\u062a\u0646\u0638\u06cc\u0645\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u0646\u062d\u0631\u0627\u0641\u0627\u062a \u0632\u0627\u0648\u06cc\u0647\u200c\u0627\u06cc<\/strong><br \/>\n\u0637\u0631\u0627\u062d\u06cc \u06a9\u0631\u0648\u06cc \u0622\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u0646\u062d\u0631\u0627\u0641\u0627\u062a \u062c\u0632\u0626\u06cc \u062f\u0631 \u0645\u062d\u0648\u0631 \u0634\u0627\u0641\u062a \u062c\u0628\u0631\u0627\u0646 \u0634\u062f\u0647 \u0648 \u0627\u0632 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f.<\/li>\n<li><strong>\u0637\u0648\u0644 \u0639\u0645\u0631 \u0628\u0627\u0644\u0627 \u0648 \u0627\u0633\u062a\u062d\u06a9\u0627\u0645 \u0633\u0627\u062e\u062a\u0627\u0631\u06cc<\/strong><br \/>\n\u0645\u0648\u0627\u062f \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0633\u0627\u062e\u062a \u062f\u0642\u06cc\u0642 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0648\u0627\u0645 \u0648 \u06a9\u0627\u0647\u0634 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062a\u0639\u0648\u06cc\u0636 \u0645\u06a9\u0631\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/li>\n<li><strong>\u06a9\u0627\u0647\u0634 \u0644\u0631\u0632\u0634 \u0648 \u0646\u0648\u06cc\u0632 \u062f\u0631 \u062d\u06cc\u0646 \u06a9\u0627\u0631\u06a9\u0631\u062f<\/strong><br \/>\n\u0637\u0631\u0627\u062d\u06cc \u0628\u0647\u06cc\u0646\u0647 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0645\u0648\u062c\u0628 \u0639\u0645\u0644\u06a9\u0631\u062f \u0622\u0631\u0627\u0645 \u0648 \u06a9\u0627\u0647\u0634 \u0635\u062f\u0627 \u062f\u0631 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0645\u06cc\u200c\u06af\u0631\u062f\u062f.<\/li>\n<li><strong>\u0646\u0635\u0628 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0622\u0633\u0627\u0646<\/strong><br \/>\n\u0628\u0627 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u0646\u0635\u0628 \u0633\u0631\u06cc\u0639 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u06a9\u0645\u200c\u0647\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/li>\n<\/ul>\n<h2>\u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc<\/h2>\n<p>\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0635\u0634 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0645\u062a\u0646\u0648\u0639\u06cc \u0628\u0647\u200c\u06a9\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f:<\/p>\n<ul>\n<li>\u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc<\/li>\n<li>\u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0646\u0648\u0627\u0631 \u0646\u0642\u0627\u0644\u0647 \u0648 \u062e\u0637\u0648\u0637 \u0627\u0646\u062a\u0642\u0627\u0644 \u0645\u0648\u0627\u062f<\/li>\n<li>\u0635\u0646\u0627\u06cc\u0639 \u0641\u0648\u0644\u0627\u062f \u0648 \u0631\u06cc\u062e\u062a\u0647\u200c\u06af\u0631\u06cc<\/li>\n<li>\u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0631\u0627\u0647\u200c\u0633\u0627\u0632\u06cc \u0648 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/li>\n<li>\u067e\u0645\u067e\u200c\u0647\u0627 \u0648 \u06a9\u0645\u067e\u0631\u0633\u0648\u0631\u0647\u0627<\/li>\n<li>\u06af\u06cc\u0631\u0628\u06a9\u0633\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u0628\u0647\u200c\u062f\u0644\u06cc\u0644 \u062a\u062d\u0645\u0644 \u0628\u0627\u0631\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f \u0648 \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631\u06cc \u0628\u0627\u0644\u0627\u060c \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u0645\u062d\u06cc\u0637\u200c\u0647\u0627\u06cc \u0633\u062e\u062a \u0648 \u062f\u0627\u0631\u0627\u06cc \u0644\u0631\u0632\u0634\u200c\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f\u060c \u0627\u0632 \u0627\u0646\u062a\u062e\u0627\u0628\u200c\u0647\u0627\u06cc \u0627\u0648\u0644 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h2>\u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc<\/h2>\n<table>\n<thead>\n<tr>\n<th>\u0645\u0634\u062e\u0635\u0647<\/th>\n<th>\u0645\u0642\u062f\u0627\u0631<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>\u0645\u062f\u0644<\/td>\n<td>22205<\/td>\n<\/tr>\n<tr>\n<td>\u0646\u0648\u0639 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af<\/td>\n<td>\u06a9\u0631\u0648\u06cc\u060c \u062f\u0648 \u0631\u062f\u06cc\u0641\u0647<\/td>\n<\/tr>\n<tr>\n<td>\u0642\u0637\u0631 \u062f\u0627\u062e\u0644\u06cc (mm)<\/td>\n<td>25<\/td>\n<\/tr>\n<tr>\n<td>\u0642\u0637\u0631 \u062e\u0627\u0631\u062c\u06cc (mm)<\/td>\n<td>52<\/td>\n<\/tr>\n<tr>\n<td>\u0639\u0631\u0636 (mm)<\/td>\n<td>15<\/td>\n<\/tr>\n<tr>\n<td>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u0631 \u0634\u0639\u0627\u0639\u06cc (kN)<\/td>\n<td>32.6<\/td>\n<\/tr>\n<tr>\n<td>\u0638\u0631\u0641\u06cc\u062a \u0628\u0627\u0631 \u0645\u062d\u0648\u0631\u06cc (kN)<\/td>\n<td>17.3<\/td>\n<\/tr>\n<tr>\n<td>\u0633\u0631\u0639\u062a \u0645\u062c\u0627\u0632 (rpm)<\/td>\n<td>11,000<\/td>\n<\/tr>\n<tr>\n<td>\u0648\u0632\u0646 (kg)<\/td>\n<td>\u062d\u062f\u0648\u062f 0.21<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>\u0686\u0631\u0627 \u062e\u0631\u06cc\u062f \u0627\u0632 MT Royal\u061f<\/h2>\n<p>\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u062f\u0631\u062e\u0634\u0627\u0646 \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u062a\u0627\u0645\u06cc\u0646 \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0627\u0632 \u062a\u0631\u06a9\u06cc\u0647\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0639\u062a\u0628\u0631\u062a\u0631\u06cc\u0646 \u062a\u0627\u0645\u06cc\u0646\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af\u200c\u0647\u0627\u06cc \u0627\u0635\u0644 \u0648 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0633\u062a. \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<ul>\n<li>\u0642\u06cc\u0645\u062a \u0631\u0642\u0627\u0628\u062a\u06cc \u0648 \u0645\u0646\u0635\u0641\u0627\u0646\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 \u0628\u0627\u0632\u0627\u0631<\/li>\n<li>\u062a\u062d\u0648\u06cc\u0644 \u0633\u0631\u06cc\u0639 \u0648 \u0645\u0646\u0638\u0645 \u0628\u0647 \u0633\u0631\u0627\u0633\u0631 \u0627\u06cc\u0631\u0627\u0646<\/li>\n<li>\u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0641\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc \u062a\u0648\u0633\u0637 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0645\u062c\u0631\u0628<\/li>\n<li>\u062a\u0636\u0645\u06cc\u0646 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0627\u0635\u0627\u0644\u062a \u06a9\u0627\u0644\u0627<\/li>\n<li>\u0645\u0634\u0627\u0648\u0631\u0647 \u0641\u0646\u06cc \u062f\u0642\u06cc\u0642 \u0648 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u062f\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644<\/li>\n<\/ul>\n<p>\u0627\u06cc\u0646 \u0645\u0632\u0627\u06cc\u0627 \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0647 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0648\u0644 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u062f.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p><strong>\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI<\/strong> \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u0645\u0642\u0627\u0648\u0645 \u062f\u0631 \u0635\u0646\u0639\u062a \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062a\u062d\u0645\u0644 \u0628\u0627\u0631\u0647\u0627\u06cc \u0634\u0639\u0627\u0639\u06cc \u0648 \u0645\u062d\u0648\u0631\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u062f\u0648 \u0631\u062f\u06cc\u0641\u0647 \u0628\u0627 \u0633\u0627\u062e\u062a\u0627\u0631 \u06a9\u0631\u0648\u06cc\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u062e\u0648\u062f\u062a\u0646\u0638\u06cc\u0645\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u0646\u062d\u0631\u0627\u0641\u0627\u062a \u0632\u0627\u0648\u06cc\u0647\u200c\u0627\u06cc \u0634\u0627\u0641\u062a \u0631\u0627 \u062f\u0627\u0631\u062f \u0648 \u062f\u0631 \u0633\u0631\u0639\u062a\u200c\u0647\u0627\u06cc \u0645\u062a\u0648\u0633\u0637 \u062a\u0627 \u0628\u0627\u0644\u0627 \u0639\u0645\u0644\u06a9\u0631\u062f \u067e\u0627\u06cc\u062f\u0627\u0631 \u0648 \u0631\u0648\u0627\u0646\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0648\u0627\u0645 \u0628\u0627\u0644\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u0644\u0631\u0632\u0634 \u0648 \u0646\u0648\u06cc\u0632\u060c \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0645\u0627\u0634\u06cc\u0646\u200c\u0622\u0644\u0627\u062a \u0633\u0646\u06af\u06cc\u0646\u060c \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0639\u062f\u0646\u06cc\u060c \u0646\u0648\u0627\u0631 \u0646\u0642\u0627\u0644\u0647\u200c\u0647\u0627\u060c \u0635\u0646\u0627\u06cc\u0639 \u0641\u0648\u0644\u0627\u062f\u060c \u0631\u0627\u0647\u200c\u0633\u0627\u0632\u06cc \u0648 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u0633\u062a. \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0631\u0627 \u0627\u0632 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f \u0627\u06cc\u0631\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u06cc \u0631\u0642\u0627\u0628\u062a\u06cc\u060c \u062a\u062d\u0648\u06cc\u0644 \u0633\u0631\u06cc\u0639 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0641\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc\u060c \u062e\u062f\u0645\u0627\u062a\u06cc \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0635\u0646\u0639\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0639\u0645\u0631 \u0645\u0641\u06cc\u062f \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0648 \u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u0622\u0646 \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u0628\u0647\u200c\u0648\u06cc\u0698\u0647 \u062f\u0631 \u0628\u062e\u0634 B2B \u0628\u0633\u06cc\u0627\u0631 \u0645\u0646\u0637\u0642\u06cc \u0648 \u0628\u0647\u200c\u0635\u0631\u0641\u0647 \u0627\u0633\u062a.<strong> \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644<\/strong> \u0628\u0627 \u062a\u0636\u0645\u06cc\u0646 \u0627\u0635\u0627\u0644\u062a \u06a9\u0627\u0644\u0627\u060c \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0648 \u0645\u0634\u0627\u0648\u0631\u0647 \u062a\u062e\u0635\u0635\u06cc\u060c \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u062a\u0627\u0645\u06cc\u0646 \u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u062f.<\/p>\n","protected":false},"featured_media":40283,"comment_status":"open","ping_status":"closed","template":"","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":""},"product_brand":[],"product_cat":[4153],"product_tag":[],"class_list":["post-39819","product","type-product","status-publish","has-post-thumbnail","product_cat-4153","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644<\/title>\n<meta name=\"description\" content=\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mtroyal.com.tr\/fa\/product\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-nachi\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI\" \/>\n<meta property=\"og:description\" content=\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mtroyal.com.tr\/fa\/product\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-nachi\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/07\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/\",\"name\":\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp\",\"datePublished\":\"2025-09-16T07:00:57+00:00\",\"description\":\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp\",\"contentUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp\",\"width\":500,\"height\":452,\"caption\":\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/product\\\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u0627\",\"item\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\",\"name\":\"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644\",\"description\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a\",\"publisher\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#organization\",\"name\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo.png\",\"width\":192,\"height\":28,\"caption\":\"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647\"},\"image\":{\"@id\":\"https:\\\/\\\/mtroyal.com.tr\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},false]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","description":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mtroyal.com.tr\/fa\/product\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-nachi\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI","og_description":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.","og_url":"https:\/\/mtroyal.com.tr\/fa\/product\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-nachi\/","og_site_name":"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","og_image":[{"width":500,"height":452,"url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/07\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/","url":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/","name":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI - \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","isPartOf":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/#primaryimage"},"image":{"@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/#primaryimage"},"thumbnailUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/07\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp","datePublished":"2025-09-16T07:00:57+00:00","description":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0648 \u062f\u0648\u0627\u0645 \u0637\u0648\u0644\u0627\u0646\u06cc\u060c \u0645\u0646\u0627\u0633\u0628 \u0635\u0646\u0627\u06cc\u0639 \u0633\u0646\u06af\u06cc\u0646 \u0648 \u0645\u0639\u062f\u0646\u06cc. \u062e\u0631\u06cc\u062f \u0627\u0632 \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u0628\u0627 \u0642\u06cc\u0645\u062a \u0645\u0646\u0627\u0633\u0628 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u062a\u062e\u0635\u0635\u06cc.","breadcrumb":{"@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/#primaryimage","url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/07\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp","contentUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2025\/07\/\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af-\u06a9\u0631\u0648\u06cc-22205-\u2014-NACHI.webp","width":500,"height":452,"caption":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI"},{"@type":"BreadcrumbList","@id":"https:\/\/mtroyal.com.tr\/fa\/product\/%d8%b1%d9%88%d9%84%d8%a8%d8%b1%db%8c%d9%86%da%af-%da%a9%d8%b1%d9%88%db%8c-22205-nachi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/mtroyal.com.tr\/fa\/"},{"@type":"ListItem","position":2,"name":"\u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u0627","item":"https:\/\/mtroyal.com.tr\/fa\/products\/"},{"@type":"ListItem","position":3,"name":"\u0631\u0648\u0644\u0628\u0631\u06cc\u0646\u06af \u06a9\u0631\u0648\u06cc 22205 \u2014 NACHI"}]},{"@type":"WebSite","@id":"https:\/\/mtroyal.com.tr\/fa\/#website","url":"https:\/\/mtroyal.com.tr\/fa\/","name":"\u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644","description":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a","publisher":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mtroyal.com.tr\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/mtroyal.com.tr\/fa\/#organization","name":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647","url":"https:\/\/mtroyal.com.tr\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2015\/07\/logo.png","contentUrl":"https:\/\/mtroyal.com.tr\/fa\/wp-content\/uploads\/2015\/07\/logo.png","width":192,"height":28,"caption":"\u0634\u0631\u06a9\u062a \u0627\u0645 \u062a\u06cc \u0631\u0648\u06cc\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0647"},"image":{"@id":"https:\/\/mtroyal.com.tr\/fa\/#\/schema\/logo\/image\/"}},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/product\/39819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/comments?post=39819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/media\/40283"}],"wp:attachment":[{"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/media?parent=39819"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/product_brand?post=39819"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/product_cat?post=39819"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mtroyal.com.tr\/fa\/wp-json\/wp\/v2\/product_tag?post=39819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}